{"id":6481,"date":"2018-08-27T10:39:44","date_gmt":"2018-08-27T14:39:44","guid":{"rendered":"http:\/\/tzedekfellowship.org\/pause-for-the-cause-update\/"},"modified":"2020-06-08T11:22:48","modified_gmt":"2020-06-08T15:22:48","slug":"pause-for-the-cause-update","status":"publish","type":"post","link":"https:\/\/tzedeksocialjusticefund.org\/es\/pause-for-the-cause-update\/","title":{"rendered":"Pause for the Cause Update"},"content":{"rendered":"<p>Queridxs amigxs,<\/p>\n<p>Esperamos que este correo electr\u00f3nico les encuentre saboreando los \u00faltimos d\u00edas de verano y la dulzura de sus queridxs amigxs y familiares. Como les compartimos a principios de este a\u00f1o, estamos tomando una \u00ab<u>pausa por la causa<\/u>\u00bb con la programaci\u00f3n de Tzedek. Queremos compartir m\u00e1s sobre c\u00f3mo llegamos aqu\u00ed, y qu\u00e9 nos espera.<\/p>\n<p>En 2012, Tzedek comenz\u00f3 como un programa de pasant\u00edas para dos j\u00f3venes adultxs jud\u00edxs. Nuestro objetivo original fue apoyar a lxs l\u00edderes emergentes de justicia social en la construcci\u00f3n de habilidades para futuras carreras en el trabajo sin fines de lucro y en la asociaci\u00f3n con organizaciones locales, espec\u00edficamente para expandir su trabajo e incorporar una perspectiva hacia los derechos LGBTQ. Desde ese momento, el programa Tzedek creci\u00f3 y se transform\u00f3. Dos pasantes se expandieron a un grupo de cinco residentes y, finalmente, a una cohorte de ocho becarixs. El objetivo del programa tambi\u00e9n evolucion\u00f3 org\u00e1nicamente, ya que las necesidades y los intereses de lxs becarixs cambiaron, as\u00ed como nuestro paisaje social y pol\u00edtico. Con el tiempo, Tzedek se centr\u00f3 m\u00e1s directamente en la justicia racial, junto con la equidad LGBTQ y la lucha contra la opresi\u00f3n antijud\u00eda. Nuestras asociaciones se expandieron a movimientos pol\u00edticos comunitarios que trabajan para crear un cambio sist\u00e9mico.<\/p>\n<p>En los \u00faltimos seis a\u00f1os, Tzedek ha tenido el placer de trabajar con treinta y tres l\u00edderes y doce organizaciones locales. Hemos organizado sesiones de Almuerzo &amp; Aprendizaje para el personal de organizaciones sin fines de lucro locales, nos hemos ofrecido como voluntarixs para apoyar el trabajo de organizaciones comunitarias, respondimos a amenazas a nuestra querida comunidad y colaboramos con m\u00e1s de 50 entrenadores y facilitadores para ofrecer la programaci\u00f3n que lxs becarixs identificaron como m\u00e1s importante para su crecimiento.<\/p>\n<p>A medida que el programa Tzedek se expandi\u00f3 y cambi\u00f3, la concesi\u00f3n de becas del Fondo Amy Mandel y Katina Rodis (AMKRF por sus siglas en ingl\u00e9s) tambi\u00e9n experiment\u00f3 cambios. Desde el principio, AMKRF dirigi\u00f3 dos tercios de su apoyo a las organizaciones jud\u00edas progresistas y un tercio a las organizaciones LGBT que trabajan por la justicia social. Las \u00e1reas clave de financiaci\u00f3n incluyeron el desarrollo de liderazgo, la lucha contra la opresi\u00f3n antijud\u00eda, la justicia racial, el empoderamiento de lxs j\u00f3venes y la organizaci\u00f3n dirigida por l\u00edderes religiosxs. En 2016, el trabajo del Fondo cambi\u00f3 sustancialmente a medida que utilizamos cada vez m\u00e1s un marco interseccional con particular atenci\u00f3n a la raza, clase, g\u00e9nero, sexualidad y estado migratorio, para guiar nuestras donaciones filantr\u00f3picas. Nuestro apoyo al liderazgo de las personas de color tambi\u00e9n ha crecido, a medida que reconocemos m\u00e1s plenamente, la importancia de apoyar el trabajo de justicia social basado en la comunidad y las personas de color.<\/p>\n<p>La historia de AMKRF y Tzedek es de crecimiento y evoluci\u00f3n, prueba y error, aprendizaje constante, oscilando a medida que surgen nuevas necesidades, y profundizando nuestra conexi\u00f3n con la comunidad de justicia social de Asheville. Para tener un mayor impacto y vivir plenamente en los valores en los que creemos, nuestro trabajo debe estar informado por una estrategia profunda y la genialidad de la comunidad de la que somos parte.<\/p>\n<p>Con el apoyo de Beth Trigg de Taproot Consulting y Tamiko Ambrose Murray de Ambrose Consulting, el programa de Tzedek y el personal de concesi\u00f3n de becas participan en un proceso de revisi\u00f3n en tres partes. Desde marzo, nos hemos enfocado en profundizar las relaciones del personal, crear an\u00e1lisis colectivos y crear un marco compartido para la investigaci\u00f3n y el redise\u00f1o futuro. Durante los pr\u00f3ximos seis meses, completaremos un proceso de investigaci\u00f3n centrado en la comunidad para que nuestra programaci\u00f3n futura y la concesi\u00f3n local de becas dentro de Carolina del Norte Occidental est\u00e9n directamente informados por lxs l\u00edderes de justicia social de Asheville, organizaciones comunitarias, ex becarixs de Tzedek y muchos otres. Finalmente, comenzaremos un proceso de redise\u00f1o y alineaci\u00f3n. El programa de Beca Tzedek y el AMKRF operar\u00e1n a partir de una estrategia y un marco compartidos, con el fin de aumentar el impacto y proporcionar una mayor transparencia en torno a nuestro trabajo local.<\/p>\n<p>A\u00fan desconocemos muchos detalles, incluyendo la forma exacta de nuestra programaci\u00f3n futura o todas las formas en que la estrategia del fondo evolucionar\u00e1 y se refinar\u00e1, pero esto es lo que sabemos. Primero, en adelante nuestro trabajo se enfocar\u00e1 directamente en apoyar el trabajo y lxs l\u00edderes que est\u00e1n comprometidxs en la creaci\u00f3n de un cambio sist\u00e9mico en Asheville. Segundo, estamos explorando c\u00f3mo la supremac\u00eda, la opresi\u00f3n, el poder y el privilegio blancos aparecen en las pr\u00e1cticas organizativas del Fondo Amy Mandel y Katina Rodis y el programa Tzedek, y cu\u00e1l ser\u00eda una cultura organizacional m\u00e1s liberadora. Estamos comprometidxs a construir esa cultura. Tercero, la integridad de nuestro trabajo y nuestra capacidad para liderar con nuestros valores depender\u00e1 de la fortaleza de nuestras relaciones internas y comunitarias.<\/p>\n<p>A medida que nuestro trabajo se desarrolla, queremos compartir este proceso con ustedes, por lo que continuaremos documentando nuestro trabajo en nuestro sitio web. Pueden esperar encontrar m\u00e1s informaci\u00f3n all\u00ed sobre lo que estamos haciendo y lo que estamos aprendiendo.<\/p>\n<p>Con amor y gratitud,<\/p>\n<p>Amy Mandel + Jennifer Langton + Marsha Davis + Lindsay Majer + Heather Laine Talley<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Queridxs amigxs, Esperamos que este correo electr\u00f3nico les encuentre saboreando los \u00faltimos d\u00edas de verano y la dulzura de sus queridxs amigxs y familiares. Como les compartimos a principios de este a\u00f1o,\u2026<\/p>\n<p class=\"readmore\"><a class=\"cta\" href=\"https:\/\/tzedeksocialjusticefund.org\/es\/pause-for-the-cause-update\/\">Lee M\u00e1s<\/a><\/p>\n","protected":false},"author":4,"featured_media":6468,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[153,147,156],"tags":[169,160,163,235],"class_list":["post-6481","post","type-post","status-publish","format-standard","has-post-thumbnail","category-asheville-es","category-perspectiva-panoramica","category-press-releases-es","tag-amkrf-es","tag-amy-mandel-and-katina-rodis-fund-es","tag-pause-for-the-cause-es","tag-tzedek-social-justice-fellowship-es","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pause for the Cause Update - Tzedek Social Justice Fund<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tzedeksocialjusticefund.org\/es\/pause-for-the-cause-update\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pause for the Cause Update - Tzedek Social Justice Fund\" \/>\n<meta property=\"og:description\" content=\"Queridxs amigxs, Esperamos que este correo electr\u00f3nico les encuentre saboreando los \u00faltimos d\u00edas de verano y la dulzura de sus queridxs amigxs y familiares. Como les compartimos a principios de este a\u00f1o,\u2026Lee M\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tzedeksocialjusticefund.org\/es\/pause-for-the-cause-update\/\" \/>\n<meta property=\"og:site_name\" content=\"Tzedek Social Justice Fund\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tzedeksocialjusticefund\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-27T14:39:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-08T15:22:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tzedeksocialjusticefund.org\/wp-content\/uploads\/2018\/08\/AMKRF-TSJF-Logo-e1535381137491.png\" \/>\n\t<meta property=\"og:image:width\" content=\"455\" \/>\n\t<meta property=\"og:image:height\" content=\"201\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Lindsay.Majer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lindsay.Majer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tzedeksocialjusticefund.org\\\/es\\\/pause-for-the-cause-update\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tzedeksocialjusticefund.org\\\/es\\\/pause-for-the-cause-update\\\/\"},\"author\":{\"name\":\"Lindsay.Majer\",\"@id\":\"https:\\\/\\\/tzedeksocialjusticefund.org\\\/es\\\/#\\\/schema\\\/person\\\/c96d03a66465798a5fe62bb1ef6e76d2\"},\"headline\":\"Pause for the Cause Update\",\"datePublished\":\"2018-08-27T14:39:44+00:00\",\"dateModified\":\"2020-06-08T15:22:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tzedeksocialjusticefund.org\\\/es\\\/pause-for-the-cause-update\\\/\"},\"wordCount\":932,\"publisher\":{\"@id\":\"https:\\\/\\\/tzedeksocialjusticefund.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tzedeksocialjusticefund.org\\\/es\\\/pause-for-the-cause-update\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tzedeksocialjusticefund.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/AMKRF-TSJF-Logo-e1535381137491.png\",\"keywords\":[\"AMKRF\",\"Amy Mandel and Katina Rodis Fund\",\"pause for the cause\",\"Tzedek Social Justice Fellowship\"],\"articleSection\":[\"Asheville\",\"Perspectiva panor\u00e1mica\",\"Press Releases\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tzedeksocialjusticefund.org\\\/es\\\/pause-for-the-cause-update\\\/\",\"url\":\"https:\\\/\\\/tzedeksocialjusticefund.org\\\/es\\\/pause-for-the-cause-update\\\/\",\"name\":\"Pause for the Cause Update - Tzedek Social Justice Fund\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tzedeksocialjusticefund.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tzedeksocialjusticefund.org\\\/es\\\/pause-for-the-cause-update\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tzedeksocialjusticefund.org\\\/es\\\/pause-for-the-cause-update\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tzedeksocialjusticefund.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/AMKRF-TSJF-Logo-e1535381137491.png\",\"datePublished\":\"2018-08-27T14:39:44+00:00\",\"dateModified\":\"2020-06-08T15:22:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tzedeksocialjusticefund.org\\\/es\\\/pause-for-the-cause-update\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tzedeksocialjusticefund.org\\\/es\\\/pause-for-the-cause-update\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tzedeksocialjusticefund.org\\\/es\\\/pause-for-the-cause-update\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tzedeksocialjusticefund.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/AMKRF-TSJF-Logo-e1535381137491.png\",\"contentUrl\":\"https:\\\/\\\/tzedeksocialjusticefund.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/AMKRF-TSJF-Logo-e1535381137491.png\",\"width\":455,\"height\":201},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tzedeksocialjusticefund.org\\\/es\\\/pause-for-the-cause-update\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tzedeksocialjusticefund.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pause for the Cause Update\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tzedeksocialjusticefund.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/tzedeksocialjusticefund.org\\\/es\\\/\",\"name\":\"Tzedek Social Justice Fund\",\"description\":\"Growing Leaders to Build Change\",\"publisher\":{\"@id\":\"https:\\\/\\\/tzedeksocialjusticefund.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tzedeksocialjusticefund.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tzedeksocialjusticefund.org\\\/es\\\/#organization\",\"name\":\"Tzedek Social Justice Fund\",\"url\":\"https:\\\/\\\/tzedeksocialjusticefund.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tzedeksocialjusticefund.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tzedeksocialjusticefund.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Tzedek-Logo-Color.png\",\"contentUrl\":\"https:\\\/\\\/tzedeksocialjusticefund.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Tzedek-Logo-Color.png\",\"width\":817,\"height\":406,\"caption\":\"Tzedek Social Justice Fund\"},\"image\":{\"@id\":\"https:\\\/\\\/tzedeksocialjusticefund.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tzedeksocialjusticefund\",\"https:\\\/\\\/www.instagram.com\\\/tzedeksocialjusticefund\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/tzedek-social-justice-fund\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCNpiSO2h1wtDOwbJoCJUzJQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tzedeksocialjusticefund.org\\\/es\\\/#\\\/schema\\\/person\\\/c96d03a66465798a5fe62bb1ef6e76d2\",\"name\":\"Lindsay.Majer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/817d2b5c654f6796d4d08f937ce4d3b861c5520467bc213badbe036ecf822283?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/817d2b5c654f6796d4d08f937ce4d3b861c5520467bc213badbe036ecf822283?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/817d2b5c654f6796d4d08f937ce4d3b861c5520467bc213badbe036ecf822283?s=96&d=mm&r=g\",\"caption\":\"Lindsay.Majer\"},\"url\":\"https:\\\/\\\/tzedeksocialjusticefund.org\\\/es\\\/author\\\/lindsay-majer\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pause for the Cause Update - Tzedek Social Justice Fund","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tzedeksocialjusticefund.org\/es\/pause-for-the-cause-update\/","og_locale":"es_ES","og_type":"article","og_title":"Pause for the Cause Update - Tzedek Social Justice Fund","og_description":"Queridxs amigxs, Esperamos que este correo electr\u00f3nico les encuentre saboreando los \u00faltimos d\u00edas de verano y la dulzura de sus queridxs amigxs y familiares. Como les compartimos a principios de este a\u00f1o,\u2026Lee M\u00e1s","og_url":"https:\/\/tzedeksocialjusticefund.org\/es\/pause-for-the-cause-update\/","og_site_name":"Tzedek Social Justice Fund","article_publisher":"https:\/\/www.facebook.com\/tzedeksocialjusticefund","article_published_time":"2018-08-27T14:39:44+00:00","article_modified_time":"2020-06-08T15:22:48+00:00","og_image":[{"width":455,"height":201,"url":"https:\/\/tzedeksocialjusticefund.org\/wp-content\/uploads\/2018\/08\/AMKRF-TSJF-Logo-e1535381137491.png","type":"image\/png"}],"author":"Lindsay.Majer","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Lindsay.Majer","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tzedeksocialjusticefund.org\/es\/pause-for-the-cause-update\/#article","isPartOf":{"@id":"https:\/\/tzedeksocialjusticefund.org\/es\/pause-for-the-cause-update\/"},"author":{"name":"Lindsay.Majer","@id":"https:\/\/tzedeksocialjusticefund.org\/es\/#\/schema\/person\/c96d03a66465798a5fe62bb1ef6e76d2"},"headline":"Pause for the Cause Update","datePublished":"2018-08-27T14:39:44+00:00","dateModified":"2020-06-08T15:22:48+00:00","mainEntityOfPage":{"@id":"https:\/\/tzedeksocialjusticefund.org\/es\/pause-for-the-cause-update\/"},"wordCount":932,"publisher":{"@id":"https:\/\/tzedeksocialjusticefund.org\/es\/#organization"},"image":{"@id":"https:\/\/tzedeksocialjusticefund.org\/es\/pause-for-the-cause-update\/#primaryimage"},"thumbnailUrl":"https:\/\/tzedeksocialjusticefund.org\/wp-content\/uploads\/2018\/08\/AMKRF-TSJF-Logo-e1535381137491.png","keywords":["AMKRF","Amy Mandel and Katina Rodis Fund","pause for the cause","Tzedek Social Justice Fellowship"],"articleSection":["Asheville","Perspectiva panor\u00e1mica","Press Releases"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/tzedeksocialjusticefund.org\/es\/pause-for-the-cause-update\/","url":"https:\/\/tzedeksocialjusticefund.org\/es\/pause-for-the-cause-update\/","name":"Pause for the Cause Update - Tzedek Social Justice Fund","isPartOf":{"@id":"https:\/\/tzedeksocialjusticefund.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tzedeksocialjusticefund.org\/es\/pause-for-the-cause-update\/#primaryimage"},"image":{"@id":"https:\/\/tzedeksocialjusticefund.org\/es\/pause-for-the-cause-update\/#primaryimage"},"thumbnailUrl":"https:\/\/tzedeksocialjusticefund.org\/wp-content\/uploads\/2018\/08\/AMKRF-TSJF-Logo-e1535381137491.png","datePublished":"2018-08-27T14:39:44+00:00","dateModified":"2020-06-08T15:22:48+00:00","breadcrumb":{"@id":"https:\/\/tzedeksocialjusticefund.org\/es\/pause-for-the-cause-update\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tzedeksocialjusticefund.org\/es\/pause-for-the-cause-update\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tzedeksocialjusticefund.org\/es\/pause-for-the-cause-update\/#primaryimage","url":"https:\/\/tzedeksocialjusticefund.org\/wp-content\/uploads\/2018\/08\/AMKRF-TSJF-Logo-e1535381137491.png","contentUrl":"https:\/\/tzedeksocialjusticefund.org\/wp-content\/uploads\/2018\/08\/AMKRF-TSJF-Logo-e1535381137491.png","width":455,"height":201},{"@type":"BreadcrumbList","@id":"https:\/\/tzedeksocialjusticefund.org\/es\/pause-for-the-cause-update\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tzedeksocialjusticefund.org\/es\/"},{"@type":"ListItem","position":2,"name":"Pause for the Cause Update"}]},{"@type":"WebSite","@id":"https:\/\/tzedeksocialjusticefund.org\/es\/#website","url":"https:\/\/tzedeksocialjusticefund.org\/es\/","name":"Tzedek Social Justice Fund","description":"Growing Leaders to Build Change","publisher":{"@id":"https:\/\/tzedeksocialjusticefund.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tzedeksocialjusticefund.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/tzedeksocialjusticefund.org\/es\/#organization","name":"Tzedek Social Justice Fund","url":"https:\/\/tzedeksocialjusticefund.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tzedeksocialjusticefund.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/tzedeksocialjusticefund.org\/wp-content\/uploads\/2022\/06\/Tzedek-Logo-Color.png","contentUrl":"https:\/\/tzedeksocialjusticefund.org\/wp-content\/uploads\/2022\/06\/Tzedek-Logo-Color.png","width":817,"height":406,"caption":"Tzedek Social Justice Fund"},"image":{"@id":"https:\/\/tzedeksocialjusticefund.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tzedeksocialjusticefund","https:\/\/www.instagram.com\/tzedeksocialjusticefund\/","https:\/\/www.linkedin.com\/company\/tzedek-social-justice-fund\/","https:\/\/www.youtube.com\/channel\/UCNpiSO2h1wtDOwbJoCJUzJQ"]},{"@type":"Person","@id":"https:\/\/tzedeksocialjusticefund.org\/es\/#\/schema\/person\/c96d03a66465798a5fe62bb1ef6e76d2","name":"Lindsay.Majer","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/817d2b5c654f6796d4d08f937ce4d3b861c5520467bc213badbe036ecf822283?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/817d2b5c654f6796d4d08f937ce4d3b861c5520467bc213badbe036ecf822283?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/817d2b5c654f6796d4d08f937ce4d3b861c5520467bc213badbe036ecf822283?s=96&d=mm&r=g","caption":"Lindsay.Majer"},"url":"https:\/\/tzedeksocialjusticefund.org\/es\/author\/lindsay-majer\/"}]}},"_links":{"self":[{"href":"https:\/\/tzedeksocialjusticefund.org\/es\/wp-json\/wp\/v2\/posts\/6481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tzedeksocialjusticefund.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tzedeksocialjusticefund.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tzedeksocialjusticefund.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/tzedeksocialjusticefund.org\/es\/wp-json\/wp\/v2\/comments?post=6481"}],"version-history":[{"count":0,"href":"https:\/\/tzedeksocialjusticefund.org\/es\/wp-json\/wp\/v2\/posts\/6481\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tzedeksocialjusticefund.org\/es\/wp-json\/wp\/v2\/media\/6468"}],"wp:attachment":[{"href":"https:\/\/tzedeksocialjusticefund.org\/es\/wp-json\/wp\/v2\/media?parent=6481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tzedeksocialjusticefund.org\/es\/wp-json\/wp\/v2\/categories?post=6481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tzedeksocialjusticefund.org\/es\/wp-json\/wp\/v2\/tags?post=6481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}